{"id":1528,"date":"2017-05-12T19:49:42","date_gmt":"2017-05-12T17:49:42","guid":{"rendered":"http:\/\/lascriticas.com\/?p=1528"},"modified":"2017-09-30T19:04:57","modified_gmt":"2017-09-30T17:04:57","slug":"dos-poemas-sobre-maternidad","status":"publish","type":"post","link":"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/","title":{"rendered":"Dos poemas sobre la maternidad"},"content":{"rendered":"<h2><span style=\"color: #ffffff;\">Dos poemas sobre la maternidad<\/span><\/h2>\n<p style=\"text-align: center;\"><b>Dummy\u00a0#21\/04<\/b><\/p>\n<p style=\"text-align: right;\">A Olmedo, Aaron, Ana, Nicole<sup>2<\/sup><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">He sido madre tantas veces\/\u00a0Innumerables partos\/Partos como diosas\/Partos que me hicieron agua\/\u00a0Doy a luz todos los d\u00edas\/\u00a0Hijos que recojo en los bares\/\u00a0Hijos que me encuentro como astros adheridos en la arena de la playa\/\u00a0Ni\u00f1os delgados y enfermos\/\u00a0Ni\u00f1os azules como la asfixia\/\u00a0Ni\u00f1os que como yo deambulan en calles sin retorno\/De d\u00f3nde viene su sangre incendiada y hacia d\u00f3nde va\/\u00a0C\u00f3mo disipar el dolor a diario\/\u00a0Caminamos todos de las manos por aceras salvajes\/<i>Take\u00a0a\u00a0walk\u00a0on\u00a0the\u00a0wild\u00a0side\u00a0my\u00a0friend\/<\/i>\u00a0Ellos pintan arco\u00edris en mi plexo\/Ellos me han dado el amor necesario\u00a0para\u00a0disipar\u00a0el caos que me habita\/<i>Take\u00a0a\u00a0walk\u00a0on\u00a0the\u00a0wild\u00a0side\u00a0babe<\/i>\/Y me dan la mano\/\u00a0Bebemos hasta hincharnos como globos de helio\/ Bebemos y la ciudad se convierte en una sinfon\u00eda dulce y et\u00e9rea\/Colores venenosos se inyectan en nuestro iris\/Y nadie entiende nuestro amor\/ Nos echan de la plaza por besarnos a siete bocas\/\u00a0Nos echan de los bares por meter las palmas en las v\u00edsceras\/\u00a0nos echan de las calles nos echan\/Nadie entiende un amor de m\u00e1s de dos cabezas\/\u00a0Take\u00a0a\u00a0walk\u00a0on\u00a0the\u00a0wild\u00a0side\u00a0peque\u00f1a cosita sexy como\u00a0anarkocumbia\u00a0de la madrugada\/\u00a0Y nos tomamos de las\u00a0manos\/\u00a0La\u00a0acera salvaje tiembla nosotros temblamos con ella\/\u00a0Take\u00a0a\u00a0walk\u00a0on\u00a0the\u00a0wild\u00a0side\u00a0miamor\u00a0la noche nunca m\u00e1s llorar\u00e1 a solas.<\/p>\n<p style=\"text-align: center;\"><b>Dummy\u00a0#320<\/b><\/p>\n<p style=\"text-align: right;\"><i>A Olmedo Guerra, Anthony Guerrero y Pedro\u00a0Gonzalez\u00a0Celleri\u00a0(+)<\/i><\/p>\n<p style=\"text-align: justify;\">Todo lo visualizo en ca\u00edda. Ca\u00edda de papeles. Pesados papeles\u00a0llueven y destrozan. Preciosos ni\u00f1os lastimados caminan bajo mi plexo. C\u00f3mo no escucharlos cantar. Cual ca\u00edda sus voces. No he podido\u00a0conciliar\u00a0el sue\u00f1o desde hace un siglo. El sue\u00f1o hace que me pierda de la vida. Es lo m\u00e1s cercano a la muerte. Pero sin cerrar los ojos. Momento\u00a0alucin\u00f3geno\u00a0cuando solo son murmullos. Como un millar de campanas balance\u00e1ndose en mi sangre. Preciosos ni\u00f1os con olor a sexo. Olor que se desprende de la c\u00f3pula de la miseria y la desolaci\u00f3n. No. Yo no quise ser todos esos ni\u00f1os\u00a0corro\u00eddos\u00a0por la locura. Ni\u00f1os decantados. Ni\u00f1os de ozono y agua de mar. \u00bfD\u00f3nde sus cuerpos d\u00e9biles reposaran esperando el canto definitivo? Reyes\u00a0y reinas de tatuajes y l\u00e1grimas de barcos sobre los pechos y corazones rotos dibujados con navajas en el pubis. Preciosos ni\u00f1os corruptos con nicotina en medio, en el intersticio vac\u00edo abismal entre el coraz\u00f3n y el estern\u00f3n con las gl\u00e1ndulas nasales infladas de confeti blanco. Bellos ni\u00f1os de ropa ajustada y rota\u00a0ojeras lilas y cabelleras de caracol. Ni\u00f1os que duermen en la calles teniendo m\u00e1s de una casa esperando tibia\u00a0por\u00a0ellos. Ni\u00f1os preciosos con la luna como un\u00a0piercing\u00a0en la lengua. Locura que no llega a concretarse. Preciosos ni\u00f1os vengan a m\u00ed. Aniden en la guerra de mi vientre. Vientre de animal\/hembra degollado.\u00a0Hacinen\u00a0en la huelga de mi ombligo. Vengan a m\u00ed. jam\u00e1s ni ustedes ni yo\u00a0volveremos\u00a0a estar solos.<\/p>\n<hr \/>\n<p style=\"text-align: justify;\"><span style=\"font-family: 'trebuchet ms', geneva, sans-serif;\"><b>Yuliana Ortiz Ruano\u00a0(Esmeraldas, Ecuador, 1992)<\/b>.<b>\u00a0<\/b><\/span><span style=\"font-family: 'trebuchet ms', geneva, sans-serif;\">Gestora literaria independiente. Consta en Antolog\u00eda\u00a0<i>La Muchedumbre de tu Risa\u00a0<\/i>(Casa de la Cultura, 2014),\u00a0<i>Harawiq<\/i>\u00a0muestra de poes\u00eda ecuatoriana y boliviana (Murcielagario Kartonera, 2015). Ha participado en: Festival Internacional de Poes\u00eda\u00a0<i>Enero en la Palabra<\/i>\u00a0(Cusco, Per\u00fa 2016), Octava edici\u00f3n de\u00a0<i>Poes\u00eda en Paralelo 0<\/i>\u00a0(Ecuador, 2016).\u00a0<i>FIRAL<\/i>\u00a0(Rancagua, Chile, 2016),\u00a0<i>Todos tus cr\u00edmenes quedar\u00e1n impunes<\/i>\u00a0(Fundaci\u00f3n Pablo Neruda, Santiago de Chile, 2016). Ha publicado\u00a0<i>SOVOZ<\/i>\u00a0(<a href=\"https:\/\/www.facebook.com\/hananharawi\/\">Hanan Harawi<\/a>, <em>Todos tus cr\u00edmenes quedar\u00e1n impunes<\/em>, co-edici\u00f3n peruana ecuatoriana, 2016). Obtuvo la segunda menci\u00f3n de honor en el concurso <i>Poes\u00eda en Paralelo 0<\/i> 2017 con su segundo poemario in\u00e9dito <i>Canciones desde el fin del mundo<\/i>.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos poemas sobre la maternidad Dummy\u00a0#21\/04 A Olmedo, Aaron, Ana, Nicole2 &nbsp; He sido madre tantas veces\/\u00a0Innumerables partos\/Partos como diosas\/Partos que me hicieron agua\/\u00a0Doy a luz todos los d\u00edas\/\u00a0Hijos que recojo en los bares\/\u00a0Hijos que me encuentro como astros adheridos en la arena de la playa\/\u00a0Ni\u00f1os delgados y enfermos\/\u00a0Ni\u00f1os azules como la asfixia\/\u00a0Ni\u00f1os que como&#8230;<\/p>\n","protected":false},"author":15,"featured_media":1589,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[57,232,231,220,229,54,55,237,238],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dos poemas sobre la maternidad - Las Cr\u00edticas<\/title>\n<meta name=\"description\" content=\"Dos poemas sobre la maternidad, el parto, la infancia y la dificultad de crecer, de la poeta ecuatoriana Yuliana Ortiz\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dos poemas sobre la maternidad - Las Cr\u00edticas\" \/>\n<meta property=\"og:description\" content=\"Dos poemas sobre la maternidad, el parto, la infancia y la dificultad de crecer, de la poeta ecuatoriana Yuliana Ortiz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Las Cr\u00edticas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lascriticas\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-12T17:49:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-30T17:04:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lascriticas.com\/wp-content\/uploads\/2017\/05\/mother-1840277_1920-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yuliana Ortiz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LasCriticas_com\" \/>\n<meta name=\"twitter:site\" content=\"@LasCriticas_com\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yuliana Ortiz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/\"},\"author\":{\"name\":\"Yuliana Ortiz\",\"@id\":\"https:\/\/lascriticas.com\/#\/schema\/person\/89bd2c558fe18c83d0032961f2d20682\"},\"headline\":\"Dos poemas sobre la maternidad\",\"datePublished\":\"2017-05-12T17:49:42+00:00\",\"dateModified\":\"2017-09-30T17:04:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/\"},\"wordCount\":673,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/lascriticas.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lascriticas.com\/wp-content\/uploads\/2017\/05\/mother-1840277_1920-1.jpg\",\"keywords\":[\"maternidad\",\"ni\u00f1o\",\"ni\u00f1os\",\"parto\",\"poema\",\"poemas\",\"poes\u00eda\",\"Yuliana Ortiz\",\"Yuliana Ortiz Ruano\"],\"articleSection\":[\"Poes\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/\",\"url\":\"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/\",\"name\":\"Dos poemas sobre la maternidad - Las Cr\u00edticas\",\"isPartOf\":{\"@id\":\"https:\/\/lascriticas.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lascriticas.com\/wp-content\/uploads\/2017\/05\/mother-1840277_1920-1.jpg\",\"datePublished\":\"2017-05-12T17:49:42+00:00\",\"dateModified\":\"2017-09-30T17:04:57+00:00\",\"description\":\"Dos poemas sobre la maternidad, el parto, la infancia y la dificultad de crecer, de la poeta ecuatoriana Yuliana Ortiz\",\"breadcrumb\":{\"@id\":\"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/#primaryimage\",\"url\":\"https:\/\/lascriticas.com\/wp-content\/uploads\/2017\/05\/mother-1840277_1920-1.jpg\",\"contentUrl\":\"https:\/\/lascriticas.com\/wp-content\/uploads\/2017\/05\/mother-1840277_1920-1.jpg\",\"width\":1080,\"height\":600,\"caption\":\"Madre con su ni\u00f1o en los brazos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/lascriticas.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dos poemas sobre la maternidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lascriticas.com\/#website\",\"url\":\"https:\/\/lascriticas.com\/\",\"name\":\"Las Cr\u00edticas\",\"description\":\"Cr\u00edtica literaria hecha por mujeres\",\"publisher\":{\"@id\":\"https:\/\/lascriticas.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lascriticas.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lascriticas.com\/#organization\",\"name\":\"Las Cr\u00edticas\",\"url\":\"https:\/\/lascriticas.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/lascriticas.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lascriticas.com\/wp-content\/uploads\/2016\/09\/Las-Cr\u00edticas.png\",\"contentUrl\":\"https:\/\/lascriticas.com\/wp-content\/uploads\/2016\/09\/Las-Cr\u00edticas.png\",\"width\":372,\"height\":201,\"caption\":\"Las Cr\u00edticas\"},\"image\":{\"@id\":\"https:\/\/lascriticas.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/lascriticas\/\",\"https:\/\/x.com\/LasCriticas_com\",\"https:\/\/www.instagram.com\/lascriticas_com\/\",\"https:\/\/www.youtube.com\/channel\/UCd7r-H6EJA4sSXGLX33_iHQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/lascriticas.com\/#\/schema\/person\/89bd2c558fe18c83d0032961f2d20682\",\"name\":\"Yuliana Ortiz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/lascriticas.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9dca984e78c76a3e2fe1c19eec4fd08d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9dca984e78c76a3e2fe1c19eec4fd08d?s=96&d=mm&r=g\",\"caption\":\"Yuliana Ortiz\"},\"url\":\"https:\/\/lascriticas.com\/index.php\/author\/yuliana-ortiz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dos poemas sobre la maternidad - Las Cr\u00edticas","description":"Dos poemas sobre la maternidad, el parto, la infancia y la dificultad de crecer, de la poeta ecuatoriana Yuliana Ortiz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/","og_locale":"es_ES","og_type":"article","og_title":"Dos poemas sobre la maternidad - Las Cr\u00edticas","og_description":"Dos poemas sobre la maternidad, el parto, la infancia y la dificultad de crecer, de la poeta ecuatoriana Yuliana Ortiz","og_url":"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/","og_site_name":"Las Cr\u00edticas","article_publisher":"https:\/\/www.facebook.com\/lascriticas\/","article_published_time":"2017-05-12T17:49:42+00:00","article_modified_time":"2017-09-30T17:04:57+00:00","og_image":[{"width":1080,"height":600,"url":"https:\/\/lascriticas.com\/wp-content\/uploads\/2017\/05\/mother-1840277_1920-1.jpg","type":"image\/jpeg"}],"author":"Yuliana Ortiz","twitter_card":"summary_large_image","twitter_creator":"@LasCriticas_com","twitter_site":"@LasCriticas_com","twitter_misc":{"Escrito por":"Yuliana Ortiz","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/#article","isPartOf":{"@id":"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/"},"author":{"name":"Yuliana Ortiz","@id":"https:\/\/lascriticas.com\/#\/schema\/person\/89bd2c558fe18c83d0032961f2d20682"},"headline":"Dos poemas sobre la maternidad","datePublished":"2017-05-12T17:49:42+00:00","dateModified":"2017-09-30T17:04:57+00:00","mainEntityOfPage":{"@id":"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/"},"wordCount":673,"commentCount":0,"publisher":{"@id":"https:\/\/lascriticas.com\/#organization"},"image":{"@id":"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/#primaryimage"},"thumbnailUrl":"https:\/\/lascriticas.com\/wp-content\/uploads\/2017\/05\/mother-1840277_1920-1.jpg","keywords":["maternidad","ni\u00f1o","ni\u00f1os","parto","poema","poemas","poes\u00eda","Yuliana Ortiz","Yuliana Ortiz Ruano"],"articleSection":["Poes\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/","url":"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/","name":"Dos poemas sobre la maternidad - Las Cr\u00edticas","isPartOf":{"@id":"https:\/\/lascriticas.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/#primaryimage"},"image":{"@id":"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/#primaryimage"},"thumbnailUrl":"https:\/\/lascriticas.com\/wp-content\/uploads\/2017\/05\/mother-1840277_1920-1.jpg","datePublished":"2017-05-12T17:49:42+00:00","dateModified":"2017-09-30T17:04:57+00:00","description":"Dos poemas sobre la maternidad, el parto, la infancia y la dificultad de crecer, de la poeta ecuatoriana Yuliana Ortiz","breadcrumb":{"@id":"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/#primaryimage","url":"https:\/\/lascriticas.com\/wp-content\/uploads\/2017\/05\/mother-1840277_1920-1.jpg","contentUrl":"https:\/\/lascriticas.com\/wp-content\/uploads\/2017\/05\/mother-1840277_1920-1.jpg","width":1080,"height":600,"caption":"Madre con su ni\u00f1o en los brazos"},{"@type":"BreadcrumbList","@id":"https:\/\/lascriticas.com\/index.php\/2017\/05\/12\/dos-poemas-sobre-maternidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/lascriticas.com\/"},{"@type":"ListItem","position":2,"name":"Dos poemas sobre la maternidad"}]},{"@type":"WebSite","@id":"https:\/\/lascriticas.com\/#website","url":"https:\/\/lascriticas.com\/","name":"Las Cr\u00edticas","description":"Cr\u00edtica literaria hecha por mujeres","publisher":{"@id":"https:\/\/lascriticas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lascriticas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lascriticas.com\/#organization","name":"Las Cr\u00edticas","url":"https:\/\/lascriticas.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lascriticas.com\/#\/schema\/logo\/image\/","url":"https:\/\/lascriticas.com\/wp-content\/uploads\/2016\/09\/Las-Cr\u00edticas.png","contentUrl":"https:\/\/lascriticas.com\/wp-content\/uploads\/2016\/09\/Las-Cr\u00edticas.png","width":372,"height":201,"caption":"Las Cr\u00edticas"},"image":{"@id":"https:\/\/lascriticas.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lascriticas\/","https:\/\/x.com\/LasCriticas_com","https:\/\/www.instagram.com\/lascriticas_com\/","https:\/\/www.youtube.com\/channel\/UCd7r-H6EJA4sSXGLX33_iHQ"]},{"@type":"Person","@id":"https:\/\/lascriticas.com\/#\/schema\/person\/89bd2c558fe18c83d0032961f2d20682","name":"Yuliana Ortiz","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lascriticas.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9dca984e78c76a3e2fe1c19eec4fd08d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9dca984e78c76a3e2fe1c19eec4fd08d?s=96&d=mm&r=g","caption":"Yuliana Ortiz"},"url":"https:\/\/lascriticas.com\/index.php\/author\/yuliana-ortiz\/"}]}},"_links":{"self":[{"href":"https:\/\/lascriticas.com\/index.php\/wp-json\/wp\/v2\/posts\/1528"}],"collection":[{"href":"https:\/\/lascriticas.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lascriticas.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lascriticas.com\/index.php\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/lascriticas.com\/index.php\/wp-json\/wp\/v2\/comments?post=1528"}],"version-history":[{"count":7,"href":"https:\/\/lascriticas.com\/index.php\/wp-json\/wp\/v2\/posts\/1528\/revisions"}],"predecessor-version":[{"id":1867,"href":"https:\/\/lascriticas.com\/index.php\/wp-json\/wp\/v2\/posts\/1528\/revisions\/1867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lascriticas.com\/index.php\/wp-json\/wp\/v2\/media\/1589"}],"wp:attachment":[{"href":"https:\/\/lascriticas.com\/index.php\/wp-json\/wp\/v2\/media?parent=1528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lascriticas.com\/index.php\/wp-json\/wp\/v2\/categories?post=1528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lascriticas.com\/index.php\/wp-json\/wp\/v2\/tags?post=1528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}